{"id":1434,"date":"2021-02-26T16:48:25","date_gmt":"2021-02-26T16:48:25","guid":{"rendered":"https:\/\/www.theprintspace.com\/help\/?post_type=ht_kb&#038;p=1434"},"modified":"2021-04-19T17:51:01","modified_gmt":"2021-04-19T16:51:01","slug":"procesar-archivos-raw","status":"publish","type":"ht_kb","link":"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/","title":{"rendered":"Una gu\u00eda para procesar archivos RAW"},"content":{"rendered":"\n<p><strong>\u00bfNo est\u00e1s seguro de c\u00f3mo editar tus archivos RAW? Consulta la gu\u00eda en theprintspace sobre c\u00f3mo convertir tus archivos RAW para poder editar e imprimir tus obras de arte.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Convertir archivos RAW es un proceso directo y sencillo, pero hay unas cuantas cosas de las que deber\u00edas ser consciente.<\/p>\n\n\n\n<p>Lo primero que tienes que considerar es qu\u00e9 software usar. El mejor software es el que recomienda el fabricante de tu respaldo digital, para que pueda detectar tus ajustes de captura.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2>Paso 1: A qu\u00e9 tienes que estar atento en tus archivos RAW<\/h2>\n\n\n\n<p>Cuando tienes el software abierto, lo primero que tienes que mirar es cu\u00e1nto detalle hay en la captura RAW.&nbsp;<\/p>\n\n\n\n<p>Para la mayor\u00eda de los temas, un proceso es suficiente para producir un buen archivo con el que trabajar en Photoshop, pero con algunos archivos es \u00fatil crear varios procesos de exposiciones m\u00e1s claras y m\u00e1s oscuras.&nbsp;<\/p>\n\n\n\n<p>Puedes entonces usar estas diferentes exposiciones para pincelar m\u00e1s detalles en Photoshop.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2>Paso 2: Usar la funci\u00f3n de Aviso de Exposici\u00f3n&nbsp;<\/h2>\n\n\n\n<p>Para averiguar si la necesitas, usa la funci\u00f3n de <strong>Alerta de Exposici\u00f3n<\/strong> en tu software y comprueba si detecta un problema en alguna parte de tu imagen. Mira el ejemplo de abajo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"397\" height=\"607\" src=\"https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/02\/Processing-raw-files-theprintspace.jpg\" alt=\"\" class=\"wp-image-1060\" srcset=\"https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/02\/Processing-raw-files-theprintspace.jpg 397w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/02\/Processing-raw-files-theprintspace-196x300.jpg 196w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/02\/Processing-raw-files-theprintspace-33x50.jpg 33w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/02\/Processing-raw-files-theprintspace-39x60.jpg 39w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/02\/Processing-raw-files-theprintspace-65x100.jpg 65w\" sizes=\"(max-width: 397px) 100vw, 397px\" \/><\/figure><\/div>\n\n\n\n<p>Rojo \u2013 Aviso de detalle de iluminaci\u00f3n d\u00e9bil, Azul \u2013 aviso de detalle de sombra d\u00e9bil.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2>Paso 3: Correcci\u00f3n de color<\/h2>\n\n\n\n<p>En cuanto a la correcci\u00f3n del color en el procesamiento del software, aseg\u00farate de que el balance de blanco est\u00e9 debidamente ajustado, es decir, que sea igual a las condiciones de iluminaci\u00f3n de la toma. La c\u00e1mara deber\u00eda haber grabado esto y el software de procesamiento deber\u00eda detectarlo autom\u00e1ticamente pero puede que necesite un ajuste manual.&nbsp;<\/p>\n\n\n\n<p>En cuanto al color, la mejor opci\u00f3n ser\u00eda acercarte lo m\u00e1s posible al resultado deseado durante el procesamiento, pero a veces puede ser mejor hacer correcciones en Adobe Photoshop porque te permite hacer selecciones localizadas mientras que los convertidores de archivos RAW tienden a aplicar las correcciones a toda la imagen.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2>Paso 4: Enfoque<\/h2>\n\n\n\n<p>A esta altura, aumentar la cantidad de enfoque del archivo puede ser un problema, aunque realmente depende del uso que quieras hacer de \u00e9l. Si tienes la intenci\u00f3n de retocar los archivos entonces es mejor no aumentar la cantidad de enfoque a tu archivo y desactivar esa funci\u00f3n.<\/p>\n\n\n\n<p>A\u00f1adir enfoque puede causar problemas con la interpolaci\u00f3n del archivo, bandeado, y complicaciones con el retoque en general. Cualquier enfoque que se necesite es mejor hacer al final del proceso y no al principio. Ciertas aplicaciones, como Photoshop, tienen filtros de enfoque muy buenos.<br>&nbsp;<br>Antes de decidir qu\u00e9 ajustes quieres usar para el procesamiento de tu archivo, deber\u00edas realmente considerar para qu\u00e9 lo vas a usar. Para pasar de imagen a impresi\u00f3n la calidad es fundamental, as\u00ed que usa estas indicaciones generales para tus ajustes de salida.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2>Consejo: 8 bits vs. 16 bits<\/h2>\n\n\n\n<p>Toda impresi\u00f3n sale en 8 bits pero si eliges trabajar con archivos de 16 bits, aseg\u00farate de que los conviertes a 8 bits antes de mandarlos a imprimir. Usa el formato de archivo TIF para todo trabajo de tama\u00f1o medio y grande que imprimas.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2>\u00bfSigues sin estar seguro de c\u00f3mo procesar tus archivos RAW?<\/h2>\n\n\n\n<p><a href=\"https:\/\/www.theprintspace.com\/es\/contacta-theprintspace\/\">Contacta ya con nosotros<\/a>&nbsp;para que un miembro de nuestro equipo te eche una mano.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/app.creativehub.io\/?_ga=2.230820125.38856401.1603899773-2039470754.1602753791\"><img loading=\"lazy\" src=\"https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/03\/ES-printing-general-1024x585.png\" alt=\"\" class=\"wp-image-2432\" width=\"605\" height=\"346\" srcset=\"https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/03\/ES-printing-general-1024x585.png 1024w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/03\/ES-printing-general-300x171.png 300w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/03\/ES-printing-general-768x439.png 768w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/03\/ES-printing-general-50x29.png 50w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/03\/ES-printing-general-60x34.png 60w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/03\/ES-printing-general-100x57.png 100w, https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/03\/ES-printing-general.png 1400w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Inf\u00f3rmate sobre c\u00f3mo gestionar tus archivos RAW y usar la funci\u00f3n de aviso de exposici\u00f3n en Adobe Photoshop.<\/p>\n","protected":false},"author":2,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":[],"ht-kb-category":[254],"ht-kb-tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inf\u00f3rmate sobre c\u00f3mo procesar archivos RAW | ayuda theprintspace<\/title>\n<meta name=\"description\" content=\"Una gu\u00eda que te explica paso a paso c\u00f3mo convertir tus archivos RAW para poder editar e imprimir tus obras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inf\u00f3rmate sobre c\u00f3mo procesar archivos RAW | ayuda theprintspace\" \/>\n<meta property=\"og:description\" content=\"Una gu\u00eda que te explica paso a paso c\u00f3mo convertir tus archivos RAW para poder editar e imprimir tus obras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/\" \/>\n<meta property=\"og:site_name\" content=\"Theprintspace help\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T16:51:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/02\/Processing-raw-files-theprintspace.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\">\n\t<meta name=\"twitter:data1\" content=\"3 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.theprintspace.com\/help\/#website\",\"url\":\"https:\/\/www.theprintspace.com\/help\/\",\"name\":\"Theprintspace help\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.theprintspace.com\/help\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/#primaryimage\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/www.theprintspace.com\/help\/wp-content\/uploads\/2021\/02\/Processing-raw-files-theprintspace.jpg\",\"width\":397,\"height\":607},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/#webpage\",\"url\":\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/\",\"name\":\"Inf\\u00f3rmate sobre c\\u00f3mo procesar archivos RAW | ayuda theprintspace\",\"isPartOf\":{\"@id\":\"https:\/\/www.theprintspace.com\/help\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/#primaryimage\"},\"datePublished\":\"2021-02-26T16:48:25+00:00\",\"dateModified\":\"2021-04-19T16:51:01+00:00\",\"description\":\"Una gu\\u00eda que te explica paso a paso c\\u00f3mo convertir tus archivos RAW para poder editar e imprimir tus obras.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.theprintspace.com\/help\/nl\/knowledge-base\/\",\"url\":\"https:\/\/www.theprintspace.com\/help\/nl\/knowledge-base\/\",\"name\":\"Articles\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/\",\"url\":\"https:\/\/www.theprintspace.com\/help\/es\/knowledge-base\/procesar-archivos-raw\/\",\"name\":\"Una gu\\u00eda para procesar archivos RAW\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/ht-kb\/1434"}],"collection":[{"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/comments?post=1434"}],"version-history":[{"count":2,"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/ht-kb\/1434\/revisions"}],"predecessor-version":[{"id":3737,"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/ht-kb\/1434\/revisions\/3737"}],"wp:attachment":[{"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/media?parent=1434"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/ht-kb-category?post=1434"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/www.theprintspace.com\/help\/wp-json\/wp\/v2\/ht-kb-tag?post=1434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}